{"id":46950,"date":"2023-09-22T09:43:42","date_gmt":"2023-09-22T07:43:42","guid":{"rendered":"https:\/\/citrosars.nl\/product\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\/"},"modified":"2025-01-14T11:05:02","modified_gmt":"2025-01-14T10:05:02","slug":"tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972","status":"publish","type":"product","link":"https:\/\/citrosars.nl\/it\/prodotto\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\/","title":{"rendered":"Tubo dalla piastra del freno all&#8217;accumulatore del freno 1\/1972 &#8211;&gt;"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Tubo dalla piastra del freno all&#8217;accumulatore del freno 1\/1972 &#8211;&gt;<\/p>\n<p>6,4 mm<\/p>\n","protected":false},"featured_media":57098,"template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[351,358],"product_tag":[],"class_list":["post-46950","product","type-product","status-publish","has-post-thumbnail","product_cat-3-assali-sospensione-sterzo-organi-idraulici","product_cat-sm-it","first","instock","taxable","shipping-taxable","purchasable","product-type-simple","entry","content-bg","loop-entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tubo dalla piastra del freno all&#039;accumulatore del freno 1\/1972 -&gt; - CitroSars<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/citrosars.nl\/it\/prodotto\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tubo dalla piastra del freno all&#039;accumulatore del freno 1\/1972 -&gt; - CitroSars\" \/>\n<meta property=\"og:description\" content=\"Tubo dalla piastra del freno all&#039;accumulatore del freno 1\/1972 --&gt; 6,4 mm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/citrosars.nl\/it\/prodotto\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\/\" \/>\n<meta property=\"og:site_name\" content=\"CitroSars\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-14T10:05:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/citrosars.nl\/wp-content\/uploads\/2023\/09\/75010-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\\\/\",\"url\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\\\/\",\"name\":\"Tubo dalla piastra del freno all'accumulatore del freno 1\\\/1972 -&gt; - CitroSars\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/citrosars.nl\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1-460.jpg\",\"datePublished\":\"2023-09-22T07:43:42+00:00\",\"dateModified\":\"2025-01-14T10:05:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\\\/#primaryimage\",\"url\":\"https:\\\/\\\/citrosars.nl\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1-460.jpg\",\"contentUrl\":\"https:\\\/\\\/citrosars.nl\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1-460.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webshop\",\"item\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/webshop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tubo dalla piastra del freno all&#8217;accumulatore del freno 1\\\/1972 &#8211;&gt;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/\",\"name\":\"CitroSars\",\"description\":\"CitroSars. DS, SM Restoraton, maintainance, Revision, Sales \\\/ Restauratie, onderhoud en verkoop\",\"publisher\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/#organization\",\"name\":\"CitroSars\",\"url\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/citrosars.nl\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/citrosars-logo-02-e1638783648691.png\",\"contentUrl\":\"https:\\\/\\\/citrosars.nl\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/citrosars-logo-02-e1638783648691.png\",\"width\":1366,\"height\":324,\"caption\":\"CitroSars\"},\"image\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tubo dalla piastra del freno all'accumulatore del freno 1\/1972 -&gt; - CitroSars","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/citrosars.nl\/it\/prodotto\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\/","og_locale":"it_IT","og_type":"article","og_title":"Tubo dalla piastra del freno all'accumulatore del freno 1\/1972 -&gt; - CitroSars","og_description":"Tubo dalla piastra del freno all'accumulatore del freno 1\/1972 --&gt; 6,4 mm","og_url":"https:\/\/citrosars.nl\/it\/prodotto\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\/","og_site_name":"CitroSars","article_modified_time":"2025-01-14T10:05:02+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/citrosars.nl\/wp-content\/uploads\/2023\/09\/75010-scaled.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/citrosars.nl\/it\/prodotto\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\/","url":"https:\/\/citrosars.nl\/it\/prodotto\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\/","name":"Tubo dalla piastra del freno all'accumulatore del freno 1\/1972 -&gt; - CitroSars","isPartOf":{"@id":"https:\/\/citrosars.nl\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/citrosars.nl\/it\/prodotto\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\/#primaryimage"},"image":{"@id":"https:\/\/citrosars.nl\/it\/prodotto\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\/#primaryimage"},"thumbnailUrl":"https:\/\/citrosars.nl\/wp-content\/uploads\/2026\/03\/1-460.jpg","datePublished":"2023-09-22T07:43:42+00:00","dateModified":"2025-01-14T10:05:02+00:00","breadcrumb":{"@id":"https:\/\/citrosars.nl\/it\/prodotto\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/citrosars.nl\/it\/prodotto\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/citrosars.nl\/it\/prodotto\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\/#primaryimage","url":"https:\/\/citrosars.nl\/wp-content\/uploads\/2026\/03\/1-460.jpg","contentUrl":"https:\/\/citrosars.nl\/wp-content\/uploads\/2026\/03\/1-460.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/citrosars.nl\/it\/prodotto\/tubo-dalla-piastra-del-freno-allaccumulatore-del-freno-1-1972\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/citrosars.nl\/it\/"},{"@type":"ListItem","position":2,"name":"Webshop","item":"https:\/\/citrosars.nl\/it\/webshop\/"},{"@type":"ListItem","position":3,"name":"Tubo dalla piastra del freno all&#8217;accumulatore del freno 1\/1972 &#8211;&gt;"}]},{"@type":"WebSite","@id":"https:\/\/citrosars.nl\/it\/#website","url":"https:\/\/citrosars.nl\/it\/","name":"CitroSars","description":"CitroSars. DS, SM Restoraton, maintainance, Revision, Sales \/ Restauratie, onderhoud en verkoop","publisher":{"@id":"https:\/\/citrosars.nl\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/citrosars.nl\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/citrosars.nl\/it\/#organization","name":"CitroSars","url":"https:\/\/citrosars.nl\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/citrosars.nl\/it\/#\/schema\/logo\/image\/","url":"https:\/\/citrosars.nl\/wp-content\/uploads\/2021\/12\/citrosars-logo-02-e1638783648691.png","contentUrl":"https:\/\/citrosars.nl\/wp-content\/uploads\/2021\/12\/citrosars-logo-02-e1638783648691.png","width":1366,"height":324,"caption":"CitroSars"},"image":{"@id":"https:\/\/citrosars.nl\/it\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":{"product_cat":[{"value":351,"label":"3. Assali, sospensione, sterzo, organi idraulici."},{"value":358,"label":"SM"}]},"featured_image_src_large":["https:\/\/citrosars.nl\/wp-content\/uploads\/2026\/03\/1-460-1024x768.jpg",1024,768,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/product\/46950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/media\/57098"}],"wp:attachment":[{"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/media?parent=46950"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/product_brand?post=46950"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/product_cat?post=46950"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/product_tag?post=46950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}