{"id":45950,"date":"2024-09-19T16:16:12","date_gmt":"2024-09-19T14:16:12","guid":{"rendered":"https:\/\/citrosars.nl\/product\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\/"},"modified":"2024-12-13T11:53:37","modified_gmt":"2024-12-13T10:53:37","slug":"staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos","status":"publish","type":"product","link":"https:\/\/citrosars.nl\/it\/prodotto\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\/","title":{"rendered":"Staffa di montaggio tubo radiatore olio 2 pezzi NOS"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":52919,"template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[349,358],"product_tag":[],"class_list":["post-45950","product","type-product","status-publish","has-post-thumbnail","product_cat-1-motore-satola-cambio-comando-s-c","product_cat-sm-it","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple","entry","content-bg","loop-entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Staffa di montaggio tubo radiatore olio 2 pezzi NOS - CitroSars<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/citrosars.nl\/it\/prodotto\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Staffa di montaggio tubo radiatore olio 2 pezzi NOS - CitroSars\" \/>\n<meta property=\"og:url\" content=\"https:\/\/citrosars.nl\/it\/prodotto\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\/\" \/>\n<meta property=\"og:site_name\" content=\"CitroSars\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-13T10:53:37+00:00\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\\\/\",\"url\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\\\/\",\"name\":\"Staffa di montaggio tubo radiatore olio 2 pezzi NOS - CitroSars\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/citrosars.nl\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1-125.jpg\",\"datePublished\":\"2024-09-19T14:16:12+00:00\",\"dateModified\":\"2024-12-13T10:53:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/citrosars.nl\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1-125.jpg\",\"contentUrl\":\"https:\\\/\\\/citrosars.nl\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1-125.jpg\",\"width\":2560,\"height\":1718},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/prodotto\\\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webshop\",\"item\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/webshop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Staffa di montaggio tubo radiatore olio 2 pezzi NOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/\",\"name\":\"CitroSars\",\"description\":\"CitroSars. DS, SM Restoraton, maintainance, Revision, Sales \\\/ Restauratie, onderhoud en verkoop\",\"publisher\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/#organization\",\"name\":\"CitroSars\",\"url\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/citrosars.nl\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/citrosars-logo-02-e1638783648691.png\",\"contentUrl\":\"https:\\\/\\\/citrosars.nl\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/citrosars-logo-02-e1638783648691.png\",\"width\":1366,\"height\":324,\"caption\":\"CitroSars\"},\"image\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Staffa di montaggio tubo radiatore olio 2 pezzi NOS - CitroSars","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/citrosars.nl\/it\/prodotto\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\/","og_locale":"it_IT","og_type":"article","og_title":"Staffa di montaggio tubo radiatore olio 2 pezzi NOS - CitroSars","og_url":"https:\/\/citrosars.nl\/it\/prodotto\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\/","og_site_name":"CitroSars","article_modified_time":"2024-12-13T10:53:37+00:00","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/citrosars.nl\/it\/prodotto\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\/","url":"https:\/\/citrosars.nl\/it\/prodotto\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\/","name":"Staffa di montaggio tubo radiatore olio 2 pezzi NOS - CitroSars","isPartOf":{"@id":"https:\/\/citrosars.nl\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/citrosars.nl\/it\/prodotto\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\/#primaryimage"},"image":{"@id":"https:\/\/citrosars.nl\/it\/prodotto\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\/#primaryimage"},"thumbnailUrl":"https:\/\/citrosars.nl\/wp-content\/uploads\/2026\/03\/1-125.jpg","datePublished":"2024-09-19T14:16:12+00:00","dateModified":"2024-12-13T10:53:37+00:00","breadcrumb":{"@id":"https:\/\/citrosars.nl\/it\/prodotto\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/citrosars.nl\/it\/prodotto\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/citrosars.nl\/it\/prodotto\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\/#primaryimage","url":"https:\/\/citrosars.nl\/wp-content\/uploads\/2026\/03\/1-125.jpg","contentUrl":"https:\/\/citrosars.nl\/wp-content\/uploads\/2026\/03\/1-125.jpg","width":2560,"height":1718},{"@type":"BreadcrumbList","@id":"https:\/\/citrosars.nl\/it\/prodotto\/staffa-di-montaggio-tubo-radiatore-olio-2-pezzi-nos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/citrosars.nl\/it\/"},{"@type":"ListItem","position":2,"name":"Webshop","item":"https:\/\/citrosars.nl\/it\/webshop\/"},{"@type":"ListItem","position":3,"name":"Staffa di montaggio tubo radiatore olio 2 pezzi NOS"}]},{"@type":"WebSite","@id":"https:\/\/citrosars.nl\/it\/#website","url":"https:\/\/citrosars.nl\/it\/","name":"CitroSars","description":"CitroSars. DS, SM Restoraton, maintainance, Revision, Sales \/ Restauratie, onderhoud en verkoop","publisher":{"@id":"https:\/\/citrosars.nl\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/citrosars.nl\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/citrosars.nl\/it\/#organization","name":"CitroSars","url":"https:\/\/citrosars.nl\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/citrosars.nl\/it\/#\/schema\/logo\/image\/","url":"https:\/\/citrosars.nl\/wp-content\/uploads\/2021\/12\/citrosars-logo-02-e1638783648691.png","contentUrl":"https:\/\/citrosars.nl\/wp-content\/uploads\/2021\/12\/citrosars-logo-02-e1638783648691.png","width":1366,"height":324,"caption":"CitroSars"},"image":{"@id":"https:\/\/citrosars.nl\/it\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":{"product_cat":[{"value":349,"label":"1. SM Motore, satola cambio, comando s.c."},{"value":358,"label":"SM"}]},"featured_image_src_large":["https:\/\/citrosars.nl\/wp-content\/uploads\/2026\/03\/1-125-1024x687.jpg",1024,687,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/product\/45950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/media\/52919"}],"wp:attachment":[{"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/media?parent=45950"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/product_brand?post=45950"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/product_cat?post=45950"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/citrosars.nl\/it\/wp-json\/wp\/v2\/product_tag?post=45950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}