{"id":46462,"date":"2023-08-24T10:21:41","date_gmt":"2023-08-24T08:21:41","guid":{"rendered":"https:\/\/citrosars.nl\/product\/tube-de-fumee-dechappement-double-ds\/"},"modified":"2025-01-10T11:43:57","modified_gmt":"2025-01-10T10:43:57","slug":"tube-de-fumee-dechappement-double-ds","status":"publish","type":"product","link":"https:\/\/citrosars.nl\/fr\/produit\/tube-de-fumee-dechappement-double-ds\/","title":{"rendered":"Tube de fum\u00e9e d\u2019\u00e9chappement double DS"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":62751,"template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[370,362],"product_tag":[],"class_list":["post-46462","product","type-product","status-publish","has-post-thumbnail","product_cat-6-ds-suspension-moteur-alimentation-dessence-echappement-refroidissement-climatisation-pare-chocs","product_cat-ds-fr","first","instock","taxable","shipping-taxable","purchasable","product-type-simple","entry","content-bg","loop-entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tube de fum\u00e9e d\u2019\u00e9chappement double DS - CitroSars<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/citrosars.nl\/fr\/produit\/tube-de-fumee-dechappement-double-ds\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tube de fum\u00e9e d\u2019\u00e9chappement double DS - CitroSars\" \/>\n<meta property=\"og:url\" content=\"https:\/\/citrosars.nl\/fr\/produit\/tube-de-fumee-dechappement-double-ds\/\" \/>\n<meta property=\"og:site_name\" content=\"CitroSars\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-10T10:43:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/citrosars.nl\/wp-content\/uploads\/2023\/08\/IMG_2223-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/produit\\\/tube-de-fumee-dechappement-double-ds\\\/\",\"url\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/produit\\\/tube-de-fumee-dechappement-double-ds\\\/\",\"name\":\"Tube de fum\u00e9e d\u2019\u00e9chappement double DS - CitroSars\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/produit\\\/tube-de-fumee-dechappement-double-ds\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/produit\\\/tube-de-fumee-dechappement-double-ds\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/citrosars.nl\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1-943.jpg\",\"datePublished\":\"2023-08-24T08:21:41+00:00\",\"dateModified\":\"2025-01-10T10:43:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/produit\\\/tube-de-fumee-dechappement-double-ds\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/citrosars.nl\\\/fr\\\/produit\\\/tube-de-fumee-dechappement-double-ds\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/produit\\\/tube-de-fumee-dechappement-double-ds\\\/#primaryimage\",\"url\":\"https:\\\/\\\/citrosars.nl\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1-943.jpg\",\"contentUrl\":\"https:\\\/\\\/citrosars.nl\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1-943.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/produit\\\/tube-de-fumee-dechappement-double-ds\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webshop\",\"item\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/webshop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tube de fum\u00e9e d\u2019\u00e9chappement double DS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/\",\"name\":\"CitroSars\",\"description\":\"CitroSars. DS, SM Restoraton, maintainance, Revision, Sales \\\/ Restauratie, onderhoud en verkoop\",\"publisher\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/#organization\",\"name\":\"CitroSars\",\"url\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/citrosars.nl\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/citrosars-logo-02-e1638783648691.png\",\"contentUrl\":\"https:\\\/\\\/citrosars.nl\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/citrosars-logo-02-e1638783648691.png\",\"width\":1366,\"height\":324,\"caption\":\"CitroSars\"},\"image\":{\"@id\":\"https:\\\/\\\/citrosars.nl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tube de fum\u00e9e d\u2019\u00e9chappement double DS - CitroSars","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/citrosars.nl\/fr\/produit\/tube-de-fumee-dechappement-double-ds\/","og_locale":"fr_FR","og_type":"article","og_title":"Tube de fum\u00e9e d\u2019\u00e9chappement double DS - CitroSars","og_url":"https:\/\/citrosars.nl\/fr\/produit\/tube-de-fumee-dechappement-double-ds\/","og_site_name":"CitroSars","article_modified_time":"2025-01-10T10:43:57+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/citrosars.nl\/wp-content\/uploads\/2023\/08\/IMG_2223-scaled.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/citrosars.nl\/fr\/produit\/tube-de-fumee-dechappement-double-ds\/","url":"https:\/\/citrosars.nl\/fr\/produit\/tube-de-fumee-dechappement-double-ds\/","name":"Tube de fum\u00e9e d\u2019\u00e9chappement double DS - CitroSars","isPartOf":{"@id":"https:\/\/citrosars.nl\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/citrosars.nl\/fr\/produit\/tube-de-fumee-dechappement-double-ds\/#primaryimage"},"image":{"@id":"https:\/\/citrosars.nl\/fr\/produit\/tube-de-fumee-dechappement-double-ds\/#primaryimage"},"thumbnailUrl":"https:\/\/citrosars.nl\/wp-content\/uploads\/2026\/03\/1-943.jpg","datePublished":"2023-08-24T08:21:41+00:00","dateModified":"2025-01-10T10:43:57+00:00","breadcrumb":{"@id":"https:\/\/citrosars.nl\/fr\/produit\/tube-de-fumee-dechappement-double-ds\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/citrosars.nl\/fr\/produit\/tube-de-fumee-dechappement-double-ds\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/citrosars.nl\/fr\/produit\/tube-de-fumee-dechappement-double-ds\/#primaryimage","url":"https:\/\/citrosars.nl\/wp-content\/uploads\/2026\/03\/1-943.jpg","contentUrl":"https:\/\/citrosars.nl\/wp-content\/uploads\/2026\/03\/1-943.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/citrosars.nl\/fr\/produit\/tube-de-fumee-dechappement-double-ds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/citrosars.nl\/fr\/"},{"@type":"ListItem","position":2,"name":"Webshop","item":"https:\/\/citrosars.nl\/fr\/webshop\/"},{"@type":"ListItem","position":3,"name":"Tube de fum\u00e9e d\u2019\u00e9chappement double DS"}]},{"@type":"WebSite","@id":"https:\/\/citrosars.nl\/fr\/#website","url":"https:\/\/citrosars.nl\/fr\/","name":"CitroSars","description":"CitroSars. DS, SM Restoraton, maintainance, Revision, Sales \/ Restauratie, onderhoud en verkoop","publisher":{"@id":"https:\/\/citrosars.nl\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/citrosars.nl\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/citrosars.nl\/fr\/#organization","name":"CitroSars","url":"https:\/\/citrosars.nl\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/citrosars.nl\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/citrosars.nl\/wp-content\/uploads\/2021\/12\/citrosars-logo-02-e1638783648691.png","contentUrl":"https:\/\/citrosars.nl\/wp-content\/uploads\/2021\/12\/citrosars-logo-02-e1638783648691.png","width":1366,"height":324,"caption":"CitroSars"},"image":{"@id":"https:\/\/citrosars.nl\/fr\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":{"product_cat":[{"value":370,"label":"6. DS Suspension moteur, alimentation d&#039;essence, \u00e9chappement, refroidissement, climatisation, pare-chocs"},{"value":362,"label":"DS"}]},"featured_image_src_large":["https:\/\/citrosars.nl\/wp-content\/uploads\/2026\/03\/1-943-1024x768.jpg",1024,768,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/citrosars.nl\/fr\/wp-json\/wp\/v2\/product\/46462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/citrosars.nl\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/citrosars.nl\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/citrosars.nl\/fr\/wp-json\/wp\/v2\/media\/62751"}],"wp:attachment":[{"href":"https:\/\/citrosars.nl\/fr\/wp-json\/wp\/v2\/media?parent=46462"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/citrosars.nl\/fr\/wp-json\/wp\/v2\/product_brand?post=46462"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/citrosars.nl\/fr\/wp-json\/wp\/v2\/product_cat?post=46462"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/citrosars.nl\/fr\/wp-json\/wp\/v2\/product_tag?post=46462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}